{"id":13181,"count":2,"description":"","link":"https:\/\/mmusicmag.com\/m\/tag\/scottmulvahill\/","name":"@scottmulvahill","slug":"scottmulvahill","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/mmusicmag.com\/m\/wp-json\/wp\/v2\/tags\/13181"}],"collection":[{"href":"https:\/\/mmusicmag.com\/m\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/mmusicmag.com\/m\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/mmusicmag.com\/m\/wp-json\/wp\/v2\/posts?tags=13181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}